{"id":72107,"date":"2017-10-02T11:07:28","date_gmt":"2017-10-02T09:07:28","guid":{"rendered":"https:\/\/shawellness.com\/shamagazine\/disfruta-de-una-dieta-equilibrada\/"},"modified":"2022-11-09T20:36:45","modified_gmt":"2022-11-09T18:36:45","slug":"disfruta-de-una-dieta-equilibrada","status":"publish","type":"post","link":"https:\/\/shawellness.com\/shamagazine\/es\/disfruta-de-una-dieta-equilibrada\/","title":{"rendered":"Disfruta de una dieta equilibrada"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">Cada vez es m\u00e1s habitual hablar de<\/span><b> dieta equilibrada, comida natural,<\/b><span style=\"font-weight: 400;\"> consumo de infusiones, dietas personalizadas, ejercicio f\u00edsico, personas con alimentaci\u00f3n vegana o simplemente personas que deciden cuidarse y mimarse todos los d\u00edas.<\/span><\/p>\n<h2><span style=\"font-weight: 400;\">\u00bfQu\u00e9 es una dieta biolight?<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">Vamos a explicar de d\u00f3nde procede y para qu\u00e9 est\u00e1 indicada este tipo de dieta que hace que el cuidado dentro de un hotel pase a otro nivel.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">La <\/span><b>dieta biolight<\/b><span style=\"font-weight: 400;\"> posee una severidad media y est\u00e1 especialmente dise\u00f1ada para los hu\u00e9spedes del hotel Sha Wellness Clinic, donde te vas a cuidar un poquito m\u00e1s de lo habitual. Vas a comprender todo lo que necesitas sobre la alimentaci\u00f3n saludable y qu\u00e9 beneficios puedes obtener al llevarla a cabo sin el estr\u00e9s de los controles de peso.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Es un men\u00fa dise\u00f1ado para complementar programas antiestr\u00e9s, de rejuvenecimiento y antitabaco. La versi\u00f3n del almuerzo consta de un primer plato, un segundo plato y un postre, si as\u00ed se requiere y para la cena tan solo se ofrece un primer y un segundo plato.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Adem\u00e1s de ser un men\u00fa muy saludable, se incluye pasta un par de veces a la semana, permite el consumo de frutos secos, incluye pescado 3 veces por semana y se puede utilizar aceite.<\/span><\/p>\n<h3><span style=\"font-weight: 400;\">Composici\u00f3n e informaci\u00f3n nutricional<\/span><\/h3>\n<p><span style=\"font-weight: 400;\">Esta dieta est\u00e1<\/span><b> basada en el principio del ying y el yang <\/b><span style=\"font-weight: 400;\">y, sobre todo, se basa en<\/span><b> comida natural<\/b><span style=\"font-weight: 400;\"> como las algas, soja, cereales integrales y un largo etc\u00e9tera. Es decir, aquellos productos que no sufren manipulaci\u00f3n, que son de temporada y que se cultivan en tu entorno.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Es muy importante una personalizaci\u00f3n<\/span><b> <\/b><span style=\"font-weight: 400;\">acorde a las circunstancias personales de cada uno, asesorados siempre por un profesional.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">La diferencia entre una dieta de este tipo y una tradicional podemos observarla en sus alimentos principales:<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En una<\/span><b> dieta biolight<\/b><span style=\"font-weight: 400;\"> podemos hablar de productos principales como cereales integrales, vegetales, legumbres, algas marinas o pepinillos de consumo diario. Mientras, en una dieta tradicional hablamos de arroz, pasta, carne, pollo, la misma cantidad de agua que de pan o cereal, frutas y verduras, huevos y pescado, leche y sus derivados y adem\u00e1s, dulces y grasas en peque\u00f1a cantidad.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Para continuar, hablamos de que es necesaria la ingesta de frutas, nueces, pescado, mariscos y semillas de forma semanal. Mensualmente puedes consumir de forma opcional huevos, carnes rojas, aves y l\u00e1cteos.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">La <\/span><b>dieta biolight<\/b><span style=\"font-weight: 400;\"> contiene entre 900 y 1000 calor\u00edas de ingesta diarias y est\u00e1 indicada sobre todo para realizar una depuraci\u00f3n, por lo que no implica que pases hambre ni pierdas peso.<\/span><\/p>\n<h3><span style=\"font-weight: 400;\">\u00bfQu\u00e9 beneficios obtienes con esta forma de alimentaci\u00f3n?<\/span><\/h3>\n<p><span style=\"font-weight: 400;\">El objetivo de la dieta es<\/span><b> que aprendas a comer de forma m\u00e1s saludable<\/b><span style=\"font-weight: 400;\">, equilibrada e incorporar algo de ejercicio f\u00edsico para obtener una mayor calidad de vida. Entre los beneficios que puedes conseguir con esta <\/span><b>dieta equilibrada<\/b><span style=\"font-weight: 400;\"> podemos destacar una mayor energ\u00eda y vitalidad, menor acidez en el organismo, mejor absorci\u00f3n y digesti\u00f3n, un descanso m\u00e1s reparador y mucha m\u00e1s claridad mental y memoria. Tambi\u00e9n evita el estre\u00f1imiento, mejora la circulaci\u00f3n linf\u00e1tica, la circulaci\u00f3n sangu\u00ednea, disminuye del estr\u00e9s psicol\u00f3gico y aumenta el sistema inmunitario.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En SHA recomendamos el Programa Antiestr\u00e9s para encontrar el equilibrio y el estr\u00e9s diario que condiciona nuestra salud.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cada vez es m\u00e1s habitual hablar de dieta equilibrada, comida natural, consumo de infusiones, dietas personalizadas, ejercicio f\u00edsico, personas con alimentaci\u00f3n vegana o simplemente personas que deciden cuidarse y mimarse todos los d\u00edas. \u00bfQu\u00e9 es una dieta biolight? Vamos a explicar de d\u00f3nde procede y para qu\u00e9 est\u00e1 indicada este tipo de dieta que hace [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":74240,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1413],"tags":[],"class_list":["post-72107","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nutricion-saludable"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Descubre la mejor forma de disfrutar una dieta equilibrada y sana<\/title>\n<meta name=\"description\" content=\"La dieta biolight es una dieta equilibrada que est\u00e1 basada en el principio tao\u00edsta del ying y el yang y se encarga de ense\u00f1arnos a comer de forma saludable\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/shawellness.com\/shamagazine\/es\/disfruta-de-una-dieta-equilibrada\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Descubre la mejor forma de disfrutar una dieta equilibrada y sana\" \/>\n<meta property=\"og:description\" content=\"La dieta biolight es una dieta equilibrada que est\u00e1 basada en el principio tao\u00edsta del ying y el yang y se encarga de ense\u00f1arnos a comer de forma saludable\" \/>\n<meta property=\"og:url\" content=\"https:\/\/shawellness.com\/shamagazine\/es\/disfruta-de-una-dieta-equilibrada\/\" \/>\n<meta property=\"og:site_name\" content=\"SHA Magazine\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/shawellnessclinic\/\" \/>\n<meta property=\"article:published_time\" content=\"2017-10-02T09:07:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-09T18:36:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/shawellness.com\/shamagazine\/wp-content\/uploads\/2018\/01\/Dieta-Biolight.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"724\" \/>\n\t<meta property=\"og:image:height\" content=\"483\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"SHA\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@shawellness\" \/>\n<meta name=\"twitter:site\" content=\"@shawellness\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/shawellness.com\\\/shamagazine\\\/es\\\/disfruta-de-una-dieta-equilibrada\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/shawellness.com\\\/shamagazine\\\/es\\\/disfruta-de-una-dieta-equilibrada\\\/\"},\"author\":{\"name\":\"SHA\",\"@id\":\"https:\\\/\\\/shawellness.com\\\/shamagazine\\\/es\\\/#\\\/schema\\\/person\\\/3b72d023ae7d024728d6397054b837c3\"},\"headline\":\"Disfruta de una dieta equilibrada\",\"datePublished\":\"2017-10-02T09:07:28+00:00\",\"dateModified\":\"2022-11-09T18:36:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/shawellness.com\\\/shamagazine\\\/es\\\/disfruta-de-una-dieta-equilibrada\\\/\"},\"wordCount\":569,\"publisher\":{\"@id\":\"https:\\\/\\\/shawellness.com\\\/shamagazine\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/shawellness.com\\\/shamagazine\\\/es\\\/disfruta-de-una-dieta-equilibrada\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/shawellness.com\\\/shamagazine\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/Dieta-Biolight.jpg\",\"articleSection\":[\"Nutrici\u00f3n saludable\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/shawellness.com\\\/shamagazine\\\/es\\\/disfruta-de-una-dieta-equilibrada\\\/\",\"url\":\"https:\\\/\\\/shawellness.com\\\/shamagazine\\\/es\\\/disfruta-de-una-dieta-equilibrada\\\/\",\"name\":\"Descubre la mejor forma de disfrutar una dieta equilibrada y sana\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/shawellness.com\\\/shamagazine\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/shawellness.com\\\/shamagazine\\\/es\\\/disfruta-de-una-dieta-equilibrada\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/shawellness.com\\\/shamagazine\\\/es\\\/disfruta-de-una-dieta-equilibrada\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/shawellness.com\\\/shamagazine\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/Dieta-Biolight.jpg\",\"datePublished\":\"2017-10-02T09:07:28+00:00\",\"dateModified\":\"2022-11-09T18:36:45+00:00\",\"description\":\"La dieta biolight es una dieta equilibrada que est\u00e1 basada en el principio tao\u00edsta del ying y el yang y se encarga de ense\u00f1arnos a comer de forma saludable\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/shawellness.com\\\/shamagazine\\\/es\\\/disfruta-de-una-dieta-equilibrada\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/shawellness.com\\\/shamagazine\\\/es\\\/disfruta-de-una-dieta-equilibrada\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/shawellness.com\\\/shamagazine\\\/es\\\/disfruta-de-una-dieta-equilibrada\\\/#primaryimage\",\"url\":\"https:\\\/\\\/shawellness.com\\\/shamagazine\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/Dieta-Biolight.jpg\",\"contentUrl\":\"https:\\\/\\\/shawellness.com\\\/shamagazine\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/Dieta-Biolight.jpg\",\"width\":724,\"height\":483,\"caption\":\"Healthy homemade salads with chickpeas, bulgur and vegetables in mason jars on white wooden background. Selective focus. Copy space.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/shawellness.com\\\/shamagazine\\\/es\\\/disfruta-de-una-dieta-equilibrada\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/shawellness.com\\\/shamagazine\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Disfruta de una dieta equilibrada\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/shawellness.com\\\/shamagazine\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/shawellness.com\\\/shamagazine\\\/es\\\/\",\"name\":\"SHA Magazine\",\"description\":\"Lifelong health &amp; wellbeing\",\"publisher\":{\"@id\":\"https:\\\/\\\/shawellness.com\\\/shamagazine\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/shawellness.com\\\/shamagazine\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/shawellness.com\\\/shamagazine\\\/es\\\/#organization\",\"name\":\"SHA\",\"url\":\"https:\\\/\\\/shawellness.com\\\/shamagazine\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/shawellness.com\\\/shamagazine\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/shawellness.com\\\/shamagazine\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/sha_wellness_clinic_logo.jpg\",\"contentUrl\":\"https:\\\/\\\/shawellness.com\\\/shamagazine\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/sha_wellness_clinic_logo.jpg\",\"width\":200,\"height\":200,\"caption\":\"SHA\"},\"image\":{\"@id\":\"https:\\\/\\\/shawellness.com\\\/shamagazine\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/shawellnessclinic\\\/\",\"https:\\\/\\\/x.com\\\/shawellness\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/shawellness.com\\\/shamagazine\\\/es\\\/#\\\/schema\\\/person\\\/3b72d023ae7d024728d6397054b837c3\",\"name\":\"SHA\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Descubre la mejor forma de disfrutar una dieta equilibrada y sana","description":"La dieta biolight es una dieta equilibrada que est\u00e1 basada en el principio tao\u00edsta del ying y el yang y se encarga de ense\u00f1arnos a comer de forma saludable","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/shawellness.com\/shamagazine\/es\/disfruta-de-una-dieta-equilibrada\/","og_locale":"es_ES","og_type":"article","og_title":"Descubre la mejor forma de disfrutar una dieta equilibrada y sana","og_description":"La dieta biolight es una dieta equilibrada que est\u00e1 basada en el principio tao\u00edsta del ying y el yang y se encarga de ense\u00f1arnos a comer de forma saludable","og_url":"https:\/\/shawellness.com\/shamagazine\/es\/disfruta-de-una-dieta-equilibrada\/","og_site_name":"SHA Magazine","article_publisher":"https:\/\/www.facebook.com\/shawellnessclinic\/","article_published_time":"2017-10-02T09:07:28+00:00","article_modified_time":"2022-11-09T18:36:45+00:00","og_image":[{"width":724,"height":483,"url":"https:\/\/shawellness.com\/shamagazine\/wp-content\/uploads\/2018\/01\/Dieta-Biolight.jpg","type":"image\/jpeg"}],"author":"SHA","twitter_card":"summary_large_image","twitter_creator":"@shawellness","twitter_site":"@shawellness","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/shawellness.com\/shamagazine\/es\/disfruta-de-una-dieta-equilibrada\/#article","isPartOf":{"@id":"https:\/\/shawellness.com\/shamagazine\/es\/disfruta-de-una-dieta-equilibrada\/"},"author":{"name":"SHA","@id":"https:\/\/shawellness.com\/shamagazine\/es\/#\/schema\/person\/3b72d023ae7d024728d6397054b837c3"},"headline":"Disfruta de una dieta equilibrada","datePublished":"2017-10-02T09:07:28+00:00","dateModified":"2022-11-09T18:36:45+00:00","mainEntityOfPage":{"@id":"https:\/\/shawellness.com\/shamagazine\/es\/disfruta-de-una-dieta-equilibrada\/"},"wordCount":569,"publisher":{"@id":"https:\/\/shawellness.com\/shamagazine\/es\/#organization"},"image":{"@id":"https:\/\/shawellness.com\/shamagazine\/es\/disfruta-de-una-dieta-equilibrada\/#primaryimage"},"thumbnailUrl":"https:\/\/shawellness.com\/shamagazine\/wp-content\/uploads\/2018\/01\/Dieta-Biolight.jpg","articleSection":["Nutrici\u00f3n saludable"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/shawellness.com\/shamagazine\/es\/disfruta-de-una-dieta-equilibrada\/","url":"https:\/\/shawellness.com\/shamagazine\/es\/disfruta-de-una-dieta-equilibrada\/","name":"Descubre la mejor forma de disfrutar una dieta equilibrada y sana","isPartOf":{"@id":"https:\/\/shawellness.com\/shamagazine\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/shawellness.com\/shamagazine\/es\/disfruta-de-una-dieta-equilibrada\/#primaryimage"},"image":{"@id":"https:\/\/shawellness.com\/shamagazine\/es\/disfruta-de-una-dieta-equilibrada\/#primaryimage"},"thumbnailUrl":"https:\/\/shawellness.com\/shamagazine\/wp-content\/uploads\/2018\/01\/Dieta-Biolight.jpg","datePublished":"2017-10-02T09:07:28+00:00","dateModified":"2022-11-09T18:36:45+00:00","description":"La dieta biolight es una dieta equilibrada que est\u00e1 basada en el principio tao\u00edsta del ying y el yang y se encarga de ense\u00f1arnos a comer de forma saludable","breadcrumb":{"@id":"https:\/\/shawellness.com\/shamagazine\/es\/disfruta-de-una-dieta-equilibrada\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/shawellness.com\/shamagazine\/es\/disfruta-de-una-dieta-equilibrada\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/shawellness.com\/shamagazine\/es\/disfruta-de-una-dieta-equilibrada\/#primaryimage","url":"https:\/\/shawellness.com\/shamagazine\/wp-content\/uploads\/2018\/01\/Dieta-Biolight.jpg","contentUrl":"https:\/\/shawellness.com\/shamagazine\/wp-content\/uploads\/2018\/01\/Dieta-Biolight.jpg","width":724,"height":483,"caption":"Healthy homemade salads with chickpeas, bulgur and vegetables in mason jars on white wooden background. Selective focus. Copy space."},{"@type":"BreadcrumbList","@id":"https:\/\/shawellness.com\/shamagazine\/es\/disfruta-de-una-dieta-equilibrada\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/shawellness.com\/shamagazine\/es\/"},{"@type":"ListItem","position":2,"name":"Disfruta de una dieta equilibrada"}]},{"@type":"WebSite","@id":"https:\/\/shawellness.com\/shamagazine\/es\/#website","url":"https:\/\/shawellness.com\/shamagazine\/es\/","name":"SHA Magazine","description":"Lifelong health &amp; wellbeing","publisher":{"@id":"https:\/\/shawellness.com\/shamagazine\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/shawellness.com\/shamagazine\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/shawellness.com\/shamagazine\/es\/#organization","name":"SHA","url":"https:\/\/shawellness.com\/shamagazine\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/shawellness.com\/shamagazine\/es\/#\/schema\/logo\/image\/","url":"https:\/\/shawellness.com\/shamagazine\/wp-content\/uploads\/2025\/05\/sha_wellness_clinic_logo.jpg","contentUrl":"https:\/\/shawellness.com\/shamagazine\/wp-content\/uploads\/2025\/05\/sha_wellness_clinic_logo.jpg","width":200,"height":200,"caption":"SHA"},"image":{"@id":"https:\/\/shawellness.com\/shamagazine\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/shawellnessclinic\/","https:\/\/x.com\/shawellness"]},{"@type":"Person","@id":"https:\/\/shawellness.com\/shamagazine\/es\/#\/schema\/person\/3b72d023ae7d024728d6397054b837c3","name":"SHA"}]}},"_links":{"self":[{"href":"https:\/\/shawellness.com\/shamagazine\/es\/wp-json\/wp\/v2\/posts\/72107","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/shawellness.com\/shamagazine\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/shawellness.com\/shamagazine\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/shawellness.com\/shamagazine\/es\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/shawellness.com\/shamagazine\/es\/wp-json\/wp\/v2\/comments?post=72107"}],"version-history":[{"count":0,"href":"https:\/\/shawellness.com\/shamagazine\/es\/wp-json\/wp\/v2\/posts\/72107\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/shawellness.com\/shamagazine\/es\/wp-json\/wp\/v2\/media\/74240"}],"wp:attachment":[{"href":"https:\/\/shawellness.com\/shamagazine\/es\/wp-json\/wp\/v2\/media?parent=72107"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/shawellness.com\/shamagazine\/es\/wp-json\/wp\/v2\/categories?post=72107"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/shawellness.com\/shamagazine\/es\/wp-json\/wp\/v2\/tags?post=72107"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}