{"id":72979,"date":"2021-11-12T10:29:10","date_gmt":"2021-11-12T08:29:10","guid":{"rendered":"https:\/\/shawellness.com\/shamagazine\/la-relacion-entre-las-emociones-y-la-obesidad\/"},"modified":"2022-11-09T20:37:51","modified_gmt":"2022-11-09T18:37:51","slug":"la-relacion-entre-las-emociones-y-la-obesidad","status":"publish","type":"post","link":"https:\/\/shawellness.com\/shamagazine\/es\/la-relacion-entre-las-emociones-y-la-obesidad\/","title":{"rendered":"La relaci\u00f3n entre las emociones y la obesidad"},"content":{"rendered":"<h6><span data-contrast=\"none\">Aprender a detectar y controlar el hambre emocional es fundamental para conseguir y mantener el peso \u00f3ptimo<\/span><span data-ccp-props=\"{}\"> <\/span><\/h6>\n<p><span data-ccp-props=\"{}\"> <\/span><\/p>\n<p><span data-contrast=\"none\">La Organizaci\u00f3n Mundial de la Salud avisa de que los casos de obesidad y sobrepeso se han multiplicado por tres en todo el mundo desde 1975. Adem\u00e1s, seg\u00fan el \u00faltimo Estudio Nutricional de la Poblaci\u00f3n Espa\u00f1ola (ENPE), <\/span><b><span data-contrast=\"none\">m\u00e1s de la mitad de los espa\u00f1oles<\/span><\/b><span data-contrast=\"none\"> tiene obesidad o sobrepeso. Esto tiene un impacto directo tanto en la calidad de vida como en el aumento de los factores de riesgo de muchas enfermedades no transmisibles, como la cardiopat\u00eda coronaria, la hipertensi\u00f3n, los accidentes cerebrovasculares o la diabetes tipo 2. <\/span><span data-ccp-props=\"{}\"> <\/span><\/p>\n<p><span data-contrast=\"none\">El 12 de noviembre se celebra el D\u00eda Mundial de la Obesidad para concienciar a la sociedad de que una <\/span><b><span data-contrast=\"none\">alimentaci\u00f3n sana, energ\u00e9tica y equilibrada<\/span><\/b><span data-contrast=\"none\"> y la actividad f\u00edsica diaria son esenciales para combatir esta pandemia global. El sedentarismo y una dieta rica en alimentos procesados, az\u00facares y grasas saturadas son sus principales causas, pero la <\/span><b><span data-contrast=\"none\">gesti\u00f3n emocional<\/span><\/b><span data-contrast=\"none\"> tambi\u00e9n juega un papel decisivo. Por eso, los programas de control de peso de SHA <\/span><span data-contrast=\"auto\">no se limitan \u00fanicamente a planes personalizados de alimentaci\u00f3n y ejercicio f\u00edsico, sino que, adem\u00e1s, incluyen sesiones de mindful y emotional eating.<\/span><span data-ccp-props=\"{}\"> <\/span><\/p>\n<p><span data-contrast=\"none\">Porque comer es una necesidad vital y una fuente de placer, pero puede convertirse en una <\/span><b><span data-contrast=\"none\">v\u00eda de escape<\/span><\/b><span data-contrast=\"none\"> ante situaciones que nos provocan malestar, ansiedad, depresi\u00f3n, estr\u00e9s, miedo o incertidumbre. Por eso, durante el confinamiento, los casos de ingesta emocional crecieron de manera exponencial. Y es que, al no poder salir de casa, buscamos una satisfacci\u00f3n inmediata en la comida, por ejemplo, haciendo una tarta o un bizcocho. Como nos cuenta Cinthya Molina, psic\u00f3loga de SHA, \u201cla <\/span><b><span data-contrast=\"none\">alimentaci\u00f3n emocional<\/span><\/b><span data-contrast=\"none\"> es ingerir grandes cantidades de comida en respuesta a nuestras emociones en lugar de a la necesidad puramente fisiol\u00f3gica del hambre. Es la conexi\u00f3n directa entre el estado de \u00e1nimo y la alimentaci\u00f3n\u201d. Para evitarla, lo primero es reconocerla. Cinthya nos explica que \u201cel hambre f\u00edsica viene acompa\u00f1ada de unas <\/span><b><span data-contrast=\"none\">sensaciones muy concretas<\/span><\/b><span data-contrast=\"none\">, como sentir el est\u00f3mago vac\u00edo o falta de energ\u00eda, suele comenzar entre cuatro y cinco horas despu\u00e9s de la \u00faltima comida y, desde que empezamos a sentirla, somos capaces de esperar y podemos comer cualquier alimento. En cambio, el hambre emocional no tiene por qu\u00e9 respetar los tiempos entre comidas, suele venir precedida por pensamientos <\/span><b><span data-contrast=\"none\">centrados en la b\u00fasqueda del placer<\/span><\/b><span data-contrast=\"none\"> o para evitar el malestar y por frases como \u2018me lo merezco\u2019 o \u2018lo necesito\u2019. Adem\u00e1s, cuando tenemos hambre emocional, no nos apetece una ensalada, sino que queremos grasas, carbohidratos y az\u00facares, que son los alimentos que hist\u00f3ricamente nos han ayudado a la supervivencia y que el organismo demanda porque siente mucho confort con ellos, ya que generan <\/span><b><span data-contrast=\"none\">dopamina<\/span><\/b><span data-contrast=\"none\"> y hormonas del placer\u201d. <\/span><span data-ccp-props=\"{}\"> <\/span><\/p>\n<p><span data-contrast=\"none\">Eso s\u00ed, la b\u00fasqueda de confort en la comida es solo un s\u00edntoma de una inadecuada gesti\u00f3n emocional. Por eso, Cinthya nos invita a practicar la alimentaci\u00f3n consciente. \u201cEl <\/span><b><span data-contrast=\"none\">mindful eating<\/span><\/b><span data-contrast=\"none\"> es la capacidad de comer con atenci\u00f3n plena y atender a las necesidades del cuerpo y de la mente. El primer paso es <\/span><i><span data-contrast=\"none\">to be aware<\/span><\/i><span data-contrast=\"none\">, es decir, ser conscientes de lo que comemos y en qu\u00e9 cantidades. Despu\u00e9s, hay que comer como un cr\u00edtico gastron\u00f3mico, lo que yo llamo la <\/span><b><span data-contrast=\"none\">experiencia gourmet<\/span><\/b><span data-contrast=\"none\">: si\u00e9ntate a la mesa sin elementos alrededor que te distraigan, disfruta de los colores, los olores y las texturas de la comida, sabor\u00e9ala y trata de identificar qu\u00e9 ingredientes lleva y c\u00f3mo est\u00e1n cocinados. Por \u00faltimo, <\/span><b><span data-contrast=\"none\">come despacio<\/span><\/b><span data-contrast=\"none\"> y mastica bien los alimentos porque la hormona de la saciedad tarda 20 minutos en enviar el mensaje de que ya estamos llenos\u201d.<\/span><span data-ccp-props=\"{}\"> <\/span><\/p>\n<p><span data-contrast=\"none\">En definitiva, <\/span><b><span data-contrast=\"none\">trabajar las emociones<\/span><\/b><span data-contrast=\"none\"> y aprender nuevas v\u00edas para gestionarlas es fundamental para que la comida deje ser un refugio emocional y vuelva a ser una fuente de placer y un elemento b\u00e1sico para disfrutar de una \u00f3ptima salud f\u00edsica y mental. <\/span><span data-ccp-props=\"{}\"> <\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aprender a detectar y controlar el hambre emocional es fundamental para conseguir y mantener el peso \u00f3ptimo La Organizaci\u00f3n Mundial de la Salud avisa de que los casos de obesidad y sobrepeso se han multiplicado por tres en todo el mundo desde 1975. Adem\u00e1s, seg\u00fan el \u00faltimo Estudio Nutricional de la Poblaci\u00f3n Espa\u00f1ola (ENPE), m\u00e1s [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":76001,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1413,1425],"tags":[],"class_list":["post-72979","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nutricion-saludable","category-stayhealthywithsha-es"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La relaci\u00f3n entre las emociones y la obesidad - SHA Magazine<\/title>\n<meta name=\"description\" content=\"Aprender a detectar y controlar el hambre emocional es fundamental para conseguir y mantener el peso \u00f3ptimo La Organizaci\u00f3n Mundial de la Salud avisa de\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/shawellness.com\/shamagazine\/es\/la-relacion-entre-las-emociones-y-la-obesidad\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La relaci\u00f3n entre las emociones y la obesidad - SHA Magazine\" \/>\n<meta property=\"og:description\" content=\"Aprender a detectar y controlar el hambre emocional es fundamental para conseguir y mantener el peso \u00f3ptimo La Organizaci\u00f3n Mundial de la Salud avisa de\" \/>\n<meta property=\"og:url\" content=\"https:\/\/shawellness.com\/shamagazine\/es\/la-relacion-entre-las-emociones-y-la-obesidad\/\" \/>\n<meta property=\"og:site_name\" content=\"SHA Magazine\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/shawellnessclinic\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-12T08:29:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-09T18:37:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/shawellness.com\/shamagazine\/wp-content\/uploads\/2021\/11\/DM-obesidad-SHAmag.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"SHA\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@shawellness\" \/>\n<meta name=\"twitter:site\" content=\"@shawellness\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/shawellness.com\\\/shamagazine\\\/es\\\/la-relacion-entre-las-emociones-y-la-obesidad\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/shawellness.com\\\/shamagazine\\\/es\\\/la-relacion-entre-las-emociones-y-la-obesidad\\\/\"},\"author\":{\"name\":\"SHA\",\"@id\":\"https:\\\/\\\/shawellness.com\\\/shamagazine\\\/es\\\/#\\\/schema\\\/person\\\/3b72d023ae7d024728d6397054b837c3\"},\"headline\":\"La relaci\u00f3n entre las emociones y la obesidad\",\"datePublished\":\"2021-11-12T08:29:10+00:00\",\"dateModified\":\"2022-11-09T18:37:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/shawellness.com\\\/shamagazine\\\/es\\\/la-relacion-entre-las-emociones-y-la-obesidad\\\/\"},\"wordCount\":702,\"publisher\":{\"@id\":\"https:\\\/\\\/shawellness.com\\\/shamagazine\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/shawellness.com\\\/shamagazine\\\/es\\\/la-relacion-entre-las-emociones-y-la-obesidad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/shawellness.com\\\/shamagazine\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/DM-obesidad-SHAmag.jpg\",\"articleSection\":[\"Nutrici\u00f3n saludable\",\"StayHealthyWithSHA\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/shawellness.com\\\/shamagazine\\\/es\\\/la-relacion-entre-las-emociones-y-la-obesidad\\\/\",\"url\":\"https:\\\/\\\/shawellness.com\\\/shamagazine\\\/es\\\/la-relacion-entre-las-emociones-y-la-obesidad\\\/\",\"name\":\"La relaci\u00f3n entre las emociones y la obesidad - SHA Magazine\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/shawellness.com\\\/shamagazine\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/shawellness.com\\\/shamagazine\\\/es\\\/la-relacion-entre-las-emociones-y-la-obesidad\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/shawellness.com\\\/shamagazine\\\/es\\\/la-relacion-entre-las-emociones-y-la-obesidad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/shawellness.com\\\/shamagazine\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/DM-obesidad-SHAmag.jpg\",\"datePublished\":\"2021-11-12T08:29:10+00:00\",\"dateModified\":\"2022-11-09T18:37:51+00:00\",\"description\":\"Aprender a detectar y controlar el hambre emocional es fundamental para conseguir y mantener el peso \u00f3ptimo La Organizaci\u00f3n Mundial de la Salud avisa de\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/shawellness.com\\\/shamagazine\\\/es\\\/la-relacion-entre-las-emociones-y-la-obesidad\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/shawellness.com\\\/shamagazine\\\/es\\\/la-relacion-entre-las-emociones-y-la-obesidad\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/shawellness.com\\\/shamagazine\\\/es\\\/la-relacion-entre-las-emociones-y-la-obesidad\\\/#primaryimage\",\"url\":\"https:\\\/\\\/shawellness.com\\\/shamagazine\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/DM-obesidad-SHAmag.jpg\",\"contentUrl\":\"https:\\\/\\\/shawellness.com\\\/shamagazine\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/DM-obesidad-SHAmag.jpg\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/shawellness.com\\\/shamagazine\\\/es\\\/la-relacion-entre-las-emociones-y-la-obesidad\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/shawellness.com\\\/shamagazine\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La relaci\u00f3n entre las emociones y la obesidad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/shawellness.com\\\/shamagazine\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/shawellness.com\\\/shamagazine\\\/es\\\/\",\"name\":\"SHA Magazine\",\"description\":\"Lifelong health &amp; wellbeing\",\"publisher\":{\"@id\":\"https:\\\/\\\/shawellness.com\\\/shamagazine\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/shawellness.com\\\/shamagazine\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/shawellness.com\\\/shamagazine\\\/es\\\/#organization\",\"name\":\"SHA\",\"url\":\"https:\\\/\\\/shawellness.com\\\/shamagazine\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/shawellness.com\\\/shamagazine\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/shawellness.com\\\/shamagazine\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/sha_wellness_clinic_logo.jpg\",\"contentUrl\":\"https:\\\/\\\/shawellness.com\\\/shamagazine\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/sha_wellness_clinic_logo.jpg\",\"width\":200,\"height\":200,\"caption\":\"SHA\"},\"image\":{\"@id\":\"https:\\\/\\\/shawellness.com\\\/shamagazine\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/shawellnessclinic\\\/\",\"https:\\\/\\\/x.com\\\/shawellness\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/shawellness.com\\\/shamagazine\\\/es\\\/#\\\/schema\\\/person\\\/3b72d023ae7d024728d6397054b837c3\",\"name\":\"SHA\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La relaci\u00f3n entre las emociones y la obesidad - SHA Magazine","description":"Aprender a detectar y controlar el hambre emocional es fundamental para conseguir y mantener el peso \u00f3ptimo La Organizaci\u00f3n Mundial de la Salud avisa de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/shawellness.com\/shamagazine\/es\/la-relacion-entre-las-emociones-y-la-obesidad\/","og_locale":"es_ES","og_type":"article","og_title":"La relaci\u00f3n entre las emociones y la obesidad - SHA Magazine","og_description":"Aprender a detectar y controlar el hambre emocional es fundamental para conseguir y mantener el peso \u00f3ptimo La Organizaci\u00f3n Mundial de la Salud avisa de","og_url":"https:\/\/shawellness.com\/shamagazine\/es\/la-relacion-entre-las-emociones-y-la-obesidad\/","og_site_name":"SHA Magazine","article_publisher":"https:\/\/www.facebook.com\/shawellnessclinic\/","article_published_time":"2021-11-12T08:29:10+00:00","article_modified_time":"2022-11-09T18:37:51+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/shawellness.com\/shamagazine\/wp-content\/uploads\/2021\/11\/DM-obesidad-SHAmag.jpg","type":"image\/jpeg"}],"author":"SHA","twitter_card":"summary_large_image","twitter_creator":"@shawellness","twitter_site":"@shawellness","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/shawellness.com\/shamagazine\/es\/la-relacion-entre-las-emociones-y-la-obesidad\/#article","isPartOf":{"@id":"https:\/\/shawellness.com\/shamagazine\/es\/la-relacion-entre-las-emociones-y-la-obesidad\/"},"author":{"name":"SHA","@id":"https:\/\/shawellness.com\/shamagazine\/es\/#\/schema\/person\/3b72d023ae7d024728d6397054b837c3"},"headline":"La relaci\u00f3n entre las emociones y la obesidad","datePublished":"2021-11-12T08:29:10+00:00","dateModified":"2022-11-09T18:37:51+00:00","mainEntityOfPage":{"@id":"https:\/\/shawellness.com\/shamagazine\/es\/la-relacion-entre-las-emociones-y-la-obesidad\/"},"wordCount":702,"publisher":{"@id":"https:\/\/shawellness.com\/shamagazine\/es\/#organization"},"image":{"@id":"https:\/\/shawellness.com\/shamagazine\/es\/la-relacion-entre-las-emociones-y-la-obesidad\/#primaryimage"},"thumbnailUrl":"https:\/\/shawellness.com\/shamagazine\/wp-content\/uploads\/2021\/11\/DM-obesidad-SHAmag.jpg","articleSection":["Nutrici\u00f3n saludable","StayHealthyWithSHA"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/shawellness.com\/shamagazine\/es\/la-relacion-entre-las-emociones-y-la-obesidad\/","url":"https:\/\/shawellness.com\/shamagazine\/es\/la-relacion-entre-las-emociones-y-la-obesidad\/","name":"La relaci\u00f3n entre las emociones y la obesidad - SHA Magazine","isPartOf":{"@id":"https:\/\/shawellness.com\/shamagazine\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/shawellness.com\/shamagazine\/es\/la-relacion-entre-las-emociones-y-la-obesidad\/#primaryimage"},"image":{"@id":"https:\/\/shawellness.com\/shamagazine\/es\/la-relacion-entre-las-emociones-y-la-obesidad\/#primaryimage"},"thumbnailUrl":"https:\/\/shawellness.com\/shamagazine\/wp-content\/uploads\/2021\/11\/DM-obesidad-SHAmag.jpg","datePublished":"2021-11-12T08:29:10+00:00","dateModified":"2022-11-09T18:37:51+00:00","description":"Aprender a detectar y controlar el hambre emocional es fundamental para conseguir y mantener el peso \u00f3ptimo La Organizaci\u00f3n Mundial de la Salud avisa de","breadcrumb":{"@id":"https:\/\/shawellness.com\/shamagazine\/es\/la-relacion-entre-las-emociones-y-la-obesidad\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/shawellness.com\/shamagazine\/es\/la-relacion-entre-las-emociones-y-la-obesidad\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/shawellness.com\/shamagazine\/es\/la-relacion-entre-las-emociones-y-la-obesidad\/#primaryimage","url":"https:\/\/shawellness.com\/shamagazine\/wp-content\/uploads\/2021\/11\/DM-obesidad-SHAmag.jpg","contentUrl":"https:\/\/shawellness.com\/shamagazine\/wp-content\/uploads\/2021\/11\/DM-obesidad-SHAmag.jpg","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/shawellness.com\/shamagazine\/es\/la-relacion-entre-las-emociones-y-la-obesidad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/shawellness.com\/shamagazine\/es\/"},{"@type":"ListItem","position":2,"name":"La relaci\u00f3n entre las emociones y la obesidad"}]},{"@type":"WebSite","@id":"https:\/\/shawellness.com\/shamagazine\/es\/#website","url":"https:\/\/shawellness.com\/shamagazine\/es\/","name":"SHA Magazine","description":"Lifelong health &amp; wellbeing","publisher":{"@id":"https:\/\/shawellness.com\/shamagazine\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/shawellness.com\/shamagazine\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/shawellness.com\/shamagazine\/es\/#organization","name":"SHA","url":"https:\/\/shawellness.com\/shamagazine\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/shawellness.com\/shamagazine\/es\/#\/schema\/logo\/image\/","url":"https:\/\/shawellness.com\/shamagazine\/wp-content\/uploads\/2025\/05\/sha_wellness_clinic_logo.jpg","contentUrl":"https:\/\/shawellness.com\/shamagazine\/wp-content\/uploads\/2025\/05\/sha_wellness_clinic_logo.jpg","width":200,"height":200,"caption":"SHA"},"image":{"@id":"https:\/\/shawellness.com\/shamagazine\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/shawellnessclinic\/","https:\/\/x.com\/shawellness"]},{"@type":"Person","@id":"https:\/\/shawellness.com\/shamagazine\/es\/#\/schema\/person\/3b72d023ae7d024728d6397054b837c3","name":"SHA"}]}},"_links":{"self":[{"href":"https:\/\/shawellness.com\/shamagazine\/es\/wp-json\/wp\/v2\/posts\/72979","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/shawellness.com\/shamagazine\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/shawellness.com\/shamagazine\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/shawellness.com\/shamagazine\/es\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/shawellness.com\/shamagazine\/es\/wp-json\/wp\/v2\/comments?post=72979"}],"version-history":[{"count":0,"href":"https:\/\/shawellness.com\/shamagazine\/es\/wp-json\/wp\/v2\/posts\/72979\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/shawellness.com\/shamagazine\/es\/wp-json\/wp\/v2\/media\/76001"}],"wp:attachment":[{"href":"https:\/\/shawellness.com\/shamagazine\/es\/wp-json\/wp\/v2\/media?parent=72979"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/shawellness.com\/shamagazine\/es\/wp-json\/wp\/v2\/categories?post=72979"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/shawellness.com\/shamagazine\/es\/wp-json\/wp\/v2\/tags?post=72979"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}