{"id":72987,"date":"2021-12-01T13:59:23","date_gmt":"2021-12-01T11:59:23","guid":{"rendered":"https:\/\/shawellness.com\/shamagazine\/european-awards-in-medicine\/"},"modified":"2022-11-09T20:37:51","modified_gmt":"2022-11-09T18:37:51","slug":"european-awards-in-medicine","status":"publish","type":"post","link":"https:\/\/shawellness.com\/shamagazine\/es\/european-awards-in-medicine\/","title":{"rendered":"European Awards in Medicine"},"content":{"rendered":"<h6>Un gran impulso para nuestro compromiso con la salud<\/h6>\n<p>&nbsp;<\/p>\n<p><span data-contrast=\"auto\">El pasado martes 30 de noviembre se celebr\u00f3 en el hotel Ritz de Par\u00eds la gala de la 2\u00aa Edici\u00f3n de los European Awards in Medicine. Estos galardones, entregados por el Professional and Business Excellence Institute, reconocen la trayectoria, el esfuerzo, la determinaci\u00f3n y la creatividad de distintos profesionales especializados en diferentes \u00e1reas de la salud y promueven la excelencia y el conocimiento a trav\u00e9s de la docencia, la investigaci\u00f3n y el networking proactivo.<\/span><span data-ccp-props=\"{}\"> <\/span><\/p>\n<p><span data-ccp-props=\"{}\"> <\/span><\/p>\n<p><span data-contrast=\"auto\">Nuestro responsable de la Unidad de Medicina Preventiva y Healthy Ageing de SHA, el doctor Vicente Mera, recogi\u00f3 el premio que le acredita como mejor m\u00e9dico europeo en el campo de la Medicina Antiaging. \u201cEste galard\u00f3n me hace especial ilusi\u00f3n por dos razones. La primera, porque es un gran reconocimiento profesional. Y la segunda, porque no solo premia la labor cl\u00ednica, sino tambi\u00e9n la divulgativa. Por eso, estoy muy agradecido y lo recibo como un est\u00edmulo para seguir trabajando y mejorando\u201d.<\/span><span data-ccp-props=\"{}\"> <\/span><\/p>\n<p><span data-ccp-props=\"{}\"> <\/span><\/p>\n<p><span data-contrast=\"auto\">En 2018, en SHA desarrollamos un programa multidisciplinar de Healthy Ageing bajo la supervisi\u00f3n del doctor Mera, enfocado a retardar y disminuir los efectos del envejecimiento para disfrutar de una vida m\u00e1s plena y longeva y ser la mejor versi\u00f3n de uno mismo a cualquier edad. Para ello, se utiliz\u00f3 una metodolog\u00eda completamente personalizable basada en la nutrici\u00f3n saludable, el ejercicio f\u00edsico moderado y supervisado, la gesti\u00f3n del estr\u00e9s, la optimizaci\u00f3n del descanso y del sue\u00f1o, el equilibrio hormonal, la capacidad depurativa y metab\u00f3lica, el an\u00e1lisis del sistema inmunitario inespec\u00edfico y adaptativo y el estudio de las predisposiciones gen\u00e9ticas. La medicina preventiva y la fusi\u00f3n coordinada de nuevas \u00e1reas de conocimiento, como la terapia hormonal bioid\u00e9ntica, el asesoramiento gen\u00f3mico y epigen\u00e9tico, la evaluaci\u00f3n telom\u00e9rica y de inmunosenescencia o la aplicaci\u00f3n de c\u00e9lulas madre y plasma enriquecido, potencia notablemente el impacto positivo que todas ellas tendr\u00edan de manera individual. Este enfoque global permite recuperar la vitalidad, mejorar la apariencia f\u00edsica y optimizar el estado general de bienestar.<\/span><span data-ccp-props=\"{}\"> <\/span><\/p>\n<p><span data-ccp-props=\"{}\"> <\/span><\/p>\n<p><span data-contrast=\"auto\">Como comenta el doctor Mera, \u201cenvejecer con salud no significa \u00fanicamente la ausencia de enfermedad, sino disfrutar de un estado \u00f3ptimo de bienestar y salud f\u00edsica, mental y emocional a cualquier edad. Esto lo conseguimos evaluando y planificando de forma sistem\u00e1tica el proceso de envejecimiento lo que, a la larga, proporciona una mejora tanto de la calidad como de la expectativa de vida, a veces con esfuerzos m\u00ednimos. Adem\u00e1s, el paradigma del envejecimiento ha cambiado y la frase \u2018cualquier tiempo pasado fue mejor\u2019 ha dejado de ser cierta. El problema es que solemos conducir el coche del envejecimiento mirando por los retrovisores en lugar de por el parabrisas, lo que nos impide ver lo que nos queda por delante. Al convertir el presente en el punto de referencia vital, pensamos que lo mejor ya ha pasado. Esta mentalidad equivocada hace que nos sintamos viejos y agotados a los 50 a\u00f1os, cuando en realidad todav\u00eda nos queda mucho por hacer. Yo siempre pongo como ejemplo a David Attenborough, el cient\u00edfico, divulgador y naturalista brit\u00e1nico que, con 95 a\u00f1os, est\u00e1 m\u00e1s activo que nunca\u201d.<\/span><span data-ccp-props=\"{}\"> <\/span><\/p>\n<p><span data-ccp-props=\"{}\"> <\/span><\/p>\n<p><span data-contrast=\"auto\">En los \u00faltimos a\u00f1os, se han producido grandes avances en diversos campos m\u00e9dicos que han provocado un aumento en la esperanza de vida. De entre todos ellos, el doctor Mera destaca \u201cla investigaci\u00f3n gen\u00e9tica con nuevos biomarcadores, como la longitud de los tel\u00f3meros, los tratamientos hormonales bioid\u00e9nticos, el d\u00e9tox, los suplementos vitam\u00ednicos y la influencia de las emociones y el microbioma en el proceso de envejecimiento\u201d.<\/span><span data-ccp-props=\"{}\"> <\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un gran impulso para nuestro compromiso con la salud &nbsp; El pasado martes 30 de noviembre se celebr\u00f3 en el hotel Ritz de Par\u00eds la gala de la 2\u00aa Edici\u00f3n de los European Awards in Medicine. Estos galardones, entregados por el Professional and Business Excellence Institute, reconocen la trayectoria, el esfuerzo, la determinaci\u00f3n y la [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":76007,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1414,1425],"tags":[],"class_list":["post-72987","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-salud-y-belleza","category-stayhealthywithsha-es"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>European Awards in Medicine - SHA Magazine<\/title>\n<meta name=\"description\" content=\"Un gran impulso para nuestro compromiso con la salud &nbsp; El pasado martes 30 de noviembre se celebr\u00f3 en el hotel Ritz de Par\u00eds la gala de la 2\u00aa Edici\u00f3n\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/shawellness.com\/shamagazine\/es\/european-awards-in-medicine\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"European Awards in Medicine - SHA Magazine\" \/>\n<meta property=\"og:description\" content=\"Un gran impulso para nuestro compromiso con la salud &nbsp; El pasado martes 30 de noviembre se celebr\u00f3 en el hotel Ritz de Par\u00eds la gala de la 2\u00aa Edici\u00f3n\" \/>\n<meta property=\"og:url\" content=\"https:\/\/shawellness.com\/shamagazine\/es\/european-awards-in-medicine\/\" \/>\n<meta property=\"og:site_name\" content=\"SHA Magazine\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/shawellnessclinic\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-01T11:59:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-09T18:37:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/shawellness.com\/shamagazine\/wp-content\/uploads\/2021\/11\/Premio-Mera.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"SHA\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@shawellness\" \/>\n<meta name=\"twitter:site\" content=\"@shawellness\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/shawellness.com\\\/shamagazine\\\/es\\\/european-awards-in-medicine\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/shawellness.com\\\/shamagazine\\\/es\\\/european-awards-in-medicine\\\/\"},\"author\":{\"name\":\"SHA\",\"@id\":\"https:\\\/\\\/shawellness.com\\\/shamagazine\\\/es\\\/#\\\/schema\\\/person\\\/3b72d023ae7d024728d6397054b837c3\"},\"headline\":\"European Awards in Medicine\",\"datePublished\":\"2021-12-01T11:59:23+00:00\",\"dateModified\":\"2022-11-09T18:37:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/shawellness.com\\\/shamagazine\\\/es\\\/european-awards-in-medicine\\\/\"},\"wordCount\":631,\"publisher\":{\"@id\":\"https:\\\/\\\/shawellness.com\\\/shamagazine\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/shawellness.com\\\/shamagazine\\\/es\\\/european-awards-in-medicine\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/shawellness.com\\\/shamagazine\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/Premio-Mera.jpg\",\"articleSection\":[\"Salud y belleza\",\"StayHealthyWithSHA\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/shawellness.com\\\/shamagazine\\\/es\\\/european-awards-in-medicine\\\/\",\"url\":\"https:\\\/\\\/shawellness.com\\\/shamagazine\\\/es\\\/european-awards-in-medicine\\\/\",\"name\":\"European Awards in Medicine - SHA Magazine\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/shawellness.com\\\/shamagazine\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/shawellness.com\\\/shamagazine\\\/es\\\/european-awards-in-medicine\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/shawellness.com\\\/shamagazine\\\/es\\\/european-awards-in-medicine\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/shawellness.com\\\/shamagazine\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/Premio-Mera.jpg\",\"datePublished\":\"2021-12-01T11:59:23+00:00\",\"dateModified\":\"2022-11-09T18:37:51+00:00\",\"description\":\"Un gran impulso para nuestro compromiso con la salud &nbsp; El pasado martes 30 de noviembre se celebr\u00f3 en el hotel Ritz de Par\u00eds la gala de la 2\u00aa Edici\u00f3n\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/shawellness.com\\\/shamagazine\\\/es\\\/european-awards-in-medicine\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/shawellness.com\\\/shamagazine\\\/es\\\/european-awards-in-medicine\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/shawellness.com\\\/shamagazine\\\/es\\\/european-awards-in-medicine\\\/#primaryimage\",\"url\":\"https:\\\/\\\/shawellness.com\\\/shamagazine\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/Premio-Mera.jpg\",\"contentUrl\":\"https:\\\/\\\/shawellness.com\\\/shamagazine\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/Premio-Mera.jpg\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/shawellness.com\\\/shamagazine\\\/es\\\/european-awards-in-medicine\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/shawellness.com\\\/shamagazine\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"European Awards in Medicine\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/shawellness.com\\\/shamagazine\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/shawellness.com\\\/shamagazine\\\/es\\\/\",\"name\":\"SHA Magazine\",\"description\":\"Lifelong health &amp; wellbeing\",\"publisher\":{\"@id\":\"https:\\\/\\\/shawellness.com\\\/shamagazine\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/shawellness.com\\\/shamagazine\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/shawellness.com\\\/shamagazine\\\/es\\\/#organization\",\"name\":\"SHA\",\"url\":\"https:\\\/\\\/shawellness.com\\\/shamagazine\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/shawellness.com\\\/shamagazine\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/shawellness.com\\\/shamagazine\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/sha_wellness_clinic_logo.jpg\",\"contentUrl\":\"https:\\\/\\\/shawellness.com\\\/shamagazine\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/sha_wellness_clinic_logo.jpg\",\"width\":200,\"height\":200,\"caption\":\"SHA\"},\"image\":{\"@id\":\"https:\\\/\\\/shawellness.com\\\/shamagazine\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/shawellnessclinic\\\/\",\"https:\\\/\\\/x.com\\\/shawellness\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/shawellness.com\\\/shamagazine\\\/es\\\/#\\\/schema\\\/person\\\/3b72d023ae7d024728d6397054b837c3\",\"name\":\"SHA\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"European Awards in Medicine - SHA Magazine","description":"Un gran impulso para nuestro compromiso con la salud &nbsp; El pasado martes 30 de noviembre se celebr\u00f3 en el hotel Ritz de Par\u00eds la gala de la 2\u00aa Edici\u00f3n","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/shawellness.com\/shamagazine\/es\/european-awards-in-medicine\/","og_locale":"es_ES","og_type":"article","og_title":"European Awards in Medicine - SHA Magazine","og_description":"Un gran impulso para nuestro compromiso con la salud &nbsp; El pasado martes 30 de noviembre se celebr\u00f3 en el hotel Ritz de Par\u00eds la gala de la 2\u00aa Edici\u00f3n","og_url":"https:\/\/shawellness.com\/shamagazine\/es\/european-awards-in-medicine\/","og_site_name":"SHA Magazine","article_publisher":"https:\/\/www.facebook.com\/shawellnessclinic\/","article_published_time":"2021-12-01T11:59:23+00:00","article_modified_time":"2022-11-09T18:37:51+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/shawellness.com\/shamagazine\/wp-content\/uploads\/2021\/11\/Premio-Mera.jpg","type":"image\/jpeg"}],"author":"SHA","twitter_card":"summary_large_image","twitter_creator":"@shawellness","twitter_site":"@shawellness","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/shawellness.com\/shamagazine\/es\/european-awards-in-medicine\/#article","isPartOf":{"@id":"https:\/\/shawellness.com\/shamagazine\/es\/european-awards-in-medicine\/"},"author":{"name":"SHA","@id":"https:\/\/shawellness.com\/shamagazine\/es\/#\/schema\/person\/3b72d023ae7d024728d6397054b837c3"},"headline":"European Awards in Medicine","datePublished":"2021-12-01T11:59:23+00:00","dateModified":"2022-11-09T18:37:51+00:00","mainEntityOfPage":{"@id":"https:\/\/shawellness.com\/shamagazine\/es\/european-awards-in-medicine\/"},"wordCount":631,"publisher":{"@id":"https:\/\/shawellness.com\/shamagazine\/es\/#organization"},"image":{"@id":"https:\/\/shawellness.com\/shamagazine\/es\/european-awards-in-medicine\/#primaryimage"},"thumbnailUrl":"https:\/\/shawellness.com\/shamagazine\/wp-content\/uploads\/2021\/11\/Premio-Mera.jpg","articleSection":["Salud y belleza","StayHealthyWithSHA"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/shawellness.com\/shamagazine\/es\/european-awards-in-medicine\/","url":"https:\/\/shawellness.com\/shamagazine\/es\/european-awards-in-medicine\/","name":"European Awards in Medicine - SHA Magazine","isPartOf":{"@id":"https:\/\/shawellness.com\/shamagazine\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/shawellness.com\/shamagazine\/es\/european-awards-in-medicine\/#primaryimage"},"image":{"@id":"https:\/\/shawellness.com\/shamagazine\/es\/european-awards-in-medicine\/#primaryimage"},"thumbnailUrl":"https:\/\/shawellness.com\/shamagazine\/wp-content\/uploads\/2021\/11\/Premio-Mera.jpg","datePublished":"2021-12-01T11:59:23+00:00","dateModified":"2022-11-09T18:37:51+00:00","description":"Un gran impulso para nuestro compromiso con la salud &nbsp; El pasado martes 30 de noviembre se celebr\u00f3 en el hotel Ritz de Par\u00eds la gala de la 2\u00aa Edici\u00f3n","breadcrumb":{"@id":"https:\/\/shawellness.com\/shamagazine\/es\/european-awards-in-medicine\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/shawellness.com\/shamagazine\/es\/european-awards-in-medicine\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/shawellness.com\/shamagazine\/es\/european-awards-in-medicine\/#primaryimage","url":"https:\/\/shawellness.com\/shamagazine\/wp-content\/uploads\/2021\/11\/Premio-Mera.jpg","contentUrl":"https:\/\/shawellness.com\/shamagazine\/wp-content\/uploads\/2021\/11\/Premio-Mera.jpg","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/shawellness.com\/shamagazine\/es\/european-awards-in-medicine\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/shawellness.com\/shamagazine\/es\/"},{"@type":"ListItem","position":2,"name":"European Awards in Medicine"}]},{"@type":"WebSite","@id":"https:\/\/shawellness.com\/shamagazine\/es\/#website","url":"https:\/\/shawellness.com\/shamagazine\/es\/","name":"SHA Magazine","description":"Lifelong health &amp; wellbeing","publisher":{"@id":"https:\/\/shawellness.com\/shamagazine\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/shawellness.com\/shamagazine\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/shawellness.com\/shamagazine\/es\/#organization","name":"SHA","url":"https:\/\/shawellness.com\/shamagazine\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/shawellness.com\/shamagazine\/es\/#\/schema\/logo\/image\/","url":"https:\/\/shawellness.com\/shamagazine\/wp-content\/uploads\/2025\/05\/sha_wellness_clinic_logo.jpg","contentUrl":"https:\/\/shawellness.com\/shamagazine\/wp-content\/uploads\/2025\/05\/sha_wellness_clinic_logo.jpg","width":200,"height":200,"caption":"SHA"},"image":{"@id":"https:\/\/shawellness.com\/shamagazine\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/shawellnessclinic\/","https:\/\/x.com\/shawellness"]},{"@type":"Person","@id":"https:\/\/shawellness.com\/shamagazine\/es\/#\/schema\/person\/3b72d023ae7d024728d6397054b837c3","name":"SHA"}]}},"_links":{"self":[{"href":"https:\/\/shawellness.com\/shamagazine\/es\/wp-json\/wp\/v2\/posts\/72987","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/shawellness.com\/shamagazine\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/shawellness.com\/shamagazine\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/shawellness.com\/shamagazine\/es\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/shawellness.com\/shamagazine\/es\/wp-json\/wp\/v2\/comments?post=72987"}],"version-history":[{"count":0,"href":"https:\/\/shawellness.com\/shamagazine\/es\/wp-json\/wp\/v2\/posts\/72987\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/shawellness.com\/shamagazine\/es\/wp-json\/wp\/v2\/media\/76007"}],"wp:attachment":[{"href":"https:\/\/shawellness.com\/shamagazine\/es\/wp-json\/wp\/v2\/media?parent=72987"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/shawellness.com\/shamagazine\/es\/wp-json\/wp\/v2\/categories?post=72987"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/shawellness.com\/shamagazine\/es\/wp-json\/wp\/v2\/tags?post=72987"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}